{"id":19782,"date":"2024-01-29T17:40:49","date_gmt":"2024-01-29T17:40:49","guid":{"rendered":"https:\/\/ppr.bm-cat.com\/be\/product\/godet-de-nivellement-2-000-mm-787-in\/"},"modified":"2024-03-05T21:57:27","modified_gmt":"2024-03-05T21:57:27","slug":"godet-de-nivellement-2-000-mm-787-in","status":"publish","type":"product","link":"https:\/\/bm-cat.com\/be\/produit\/godet-de-nivellement-2-000-mm-787-in\/","title":{"rendered":"Godet de nivellement 2 000 mm (78,7 in)"},"content":{"rendered":"<p>Les godets Cat<sup>\u00ae<\/sup> sont plus qu&rsquo;un accessoire, ils sont une extension de vos machines Cat. Ils sont tous parfaitement \u00e9quilibr\u00e9s pour nos pelles hydrauliques afin de vous permettre de tasser les charges sans compromettre le rendement \u00e9nerg\u00e9tique ou l&rsquo;\u00e9tat de la machine. Nous les avons con\u00e7us pour acc\u00e9l\u00e9rer le remplissage, conserver votre charge et s&rsquo;adapter \u00e0 votre t\u00e2che.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les godets Cat\u00ae sont plus qu&rsquo;un accessoire, ils sont une extension de vos machines Cat. Ils sont tous parfaitement \u00e9quilibr\u00e9s pour nos pelles hydrauliques afin de vous permettre de tasser les charges sans compromettre le rendement \u00e9nerg\u00e9tique ou l&rsquo;\u00e9tat de la machine. Nous les avons con\u00e7us pour acc\u00e9l\u00e9rer le remplissage, conserver votre charge et s&rsquo;adapter \u00e0 votre t\u00e2che.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":""},"product_feature":[],"product_cat":[2087],"product_tag":[],"class_list":{"0":"post-19782","1":"product","2":"type-product","3":"status-publish","5":"product_cat-nivellement","7":"first","8":"instock","9":"shipping-taxable","10":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/bm-cat.com\/be\/wp-json\/wp\/v2\/product\/19782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bm-cat.com\/be\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bm-cat.com\/be\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bm-cat.com\/be\/wp-json\/wp\/v2\/comments?post=19782"}],"wp:attachment":[{"href":"https:\/\/bm-cat.com\/be\/wp-json\/wp\/v2\/media?parent=19782"}],"wp:term":[{"taxonomy":"product_feature","embeddable":true,"href":"https:\/\/bm-cat.com\/be\/wp-json\/wp\/v2\/product_feature?post=19782"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bm-cat.com\/be\/wp-json\/wp\/v2\/product_cat?post=19782"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bm-cat.com\/be\/wp-json\/wp\/v2\/product_tag?post=19782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}